{"id":3199,"date":"2018-02-15T19:00:42","date_gmt":"2018-02-15T19:00:42","guid":{"rendered":"http:\/\/www.shqiperia.com\/blog\/?p=3199"},"modified":"2021-01-23T05:52:23","modified_gmt":"2021-01-23T05:52:23","slug":"piktori-mustafa-arapi-album","status":"publish","type":"post","link":"https:\/\/www.shqiperia.com\/blog\/piktori-mustafa-arapi-album\/","title":{"rendered":"Piktori Mustafa Arapi, (album). &#8211;"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"3200\" data-permalink=\"https:\/\/www.shqiperia.com\/blog\/piktori-mustafa-arapi-album\/mustafa-arapi-26\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-26.jpg?fit=551%2C389&amp;ssl=1\" data-orig-size=\"551,389\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Mustafa Arapi (26)\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-26.jpg?fit=300%2C212&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-26.jpg?fit=551%2C389&amp;ssl=1\" class=\"alignnone  wp-image-3200\" alt=\"\" src=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-26-300x212.jpg?resize=391%2C276\" width=\"391\" height=\"276\" srcset=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-26.jpg?resize=300%2C212&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-26.jpg?w=551&amp;ssl=1 551w\" sizes=\"auto, (max-width: 391px) 100vw, 391px\" \/><\/p>\n<p><b>Mustafa Arapi<\/b> ka lindur m\u00eb 23 korrik 1950 n\u00eb Tiran\u00eb. Ai u diplomua n\u00eb Akademin\u00eb e Arteve n\u00eb vitin 1979 p\u00ebr piktur\u00eb. Pas studimeve ai filloi t\u00eb punonte si restaurues i veprave t\u00eb artit bizantin n\u00eb Institutin e Monumenteve t\u00eb Kultur\u00ebs n\u00eb Tiran\u00eb. Ka punuar si profesor n\u00eb Akademin\u00eb e Arteve nga viti 1985 deri m\u00eb 1991. Pastaj, gjat\u00eb viteve 1993-2006 ishte shef i Departamentit t\u00eb Pun\u00ebve t\u00eb Artit n\u00eb Institutin e Monumenteve t\u00eb Kultur\u00ebs.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"3201\" data-permalink=\"https:\/\/www.shqiperia.com\/blog\/piktori-mustafa-arapi-album\/mustafa-arapi-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-2.jpg?fit=552%2C441&amp;ssl=1\" data-orig-size=\"552,441\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Mustafa Arapi (2)\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-2.jpg?fit=300%2C240&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-2.jpg?fit=552%2C441&amp;ssl=1\" class=\"alignnone wp-image-3201\" alt=\"\" src=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-2-300x240.jpg?resize=553%2C442\" width=\"553\" height=\"442\" srcset=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-2.jpg?resize=300%2C240&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-2.jpg?w=552&amp;ssl=1 552w\" sizes=\"auto, (max-width: 553px) 100vw, 553px\" \/> <img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"3202\" data-permalink=\"https:\/\/www.shqiperia.com\/blog\/piktori-mustafa-arapi-album\/mustafa-arapi-3\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-3.jpg?fit=552%2C436&amp;ssl=1\" data-orig-size=\"552,436\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Mustafa Arapi (3)\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-3.jpg?fit=300%2C237&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-3.jpg?fit=552%2C436&amp;ssl=1\" class=\"alignnone wp-image-3202\" alt=\"\" src=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-3-300x237.jpg?resize=554%2C438\" width=\"554\" height=\"438\" srcset=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-3.jpg?resize=300%2C237&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-3.jpg?w=552&amp;ssl=1 552w\" sizes=\"auto, (max-width: 554px) 100vw, 554px\" \/> <img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"3203\" data-permalink=\"https:\/\/www.shqiperia.com\/blog\/piktori-mustafa-arapi-album\/mustafa-arapi-4\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-4.jpg?fit=552%2C429&amp;ssl=1\" data-orig-size=\"552,429\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Mustafa Arapi (4)\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-4.jpg?fit=300%2C233&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-4.jpg?fit=552%2C429&amp;ssl=1\" class=\"alignnone wp-image-3203\" alt=\"\" src=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-4-300x233.jpg?resize=623%2C484\" width=\"623\" height=\"484\" srcset=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-4.jpg?resize=300%2C233&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-4.jpg?w=552&amp;ssl=1 552w\" sizes=\"auto, (max-width: 623px) 100vw, 623px\" \/> <img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"3204\" data-permalink=\"https:\/\/www.shqiperia.com\/blog\/piktori-mustafa-arapi-album\/mustafa-arapi-5\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-5.jpg?fit=529%2C424&amp;ssl=1\" data-orig-size=\"529,424\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Mustafa Arapi (5)\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-5.jpg?fit=300%2C240&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-5.jpg?fit=529%2C424&amp;ssl=1\" class=\"alignnone wp-image-3204\" alt=\"\" src=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-5-300x240.jpg?resize=629%2C503\" width=\"629\" height=\"503\" srcset=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-5.jpg?resize=300%2C240&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-5.jpg?w=529&amp;ssl=1 529w\" sizes=\"auto, (max-width: 629px) 100vw, 629px\" \/> <img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"3205\" data-permalink=\"https:\/\/www.shqiperia.com\/blog\/piktori-mustafa-arapi-album\/mustafa-arapi-6\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-6.jpg?fit=552%2C506&amp;ssl=1\" data-orig-size=\"552,506\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Mustafa Arapi (6)\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-6.jpg?fit=300%2C275&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-6.jpg?fit=552%2C506&amp;ssl=1\" class=\"alignnone wp-image-3205\" alt=\"\" src=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-6-300x275.jpg?resize=528%2C484\" width=\"528\" height=\"484\" srcset=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-6.jpg?resize=300%2C275&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-6.jpg?w=552&amp;ssl=1 552w\" sizes=\"auto, (max-width: 528px) 100vw, 528px\" \/> <img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"3206\" data-permalink=\"https:\/\/www.shqiperia.com\/blog\/piktori-mustafa-arapi-album\/mustafa-arapi-7\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-7.jpg?fit=552%2C448&amp;ssl=1\" data-orig-size=\"552,448\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Mustafa Arapi (7)\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-7.jpg?fit=300%2C243&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-7.jpg?fit=552%2C448&amp;ssl=1\" class=\"alignnone wp-image-3206\" alt=\"\" src=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-7-300x243.jpg?resize=681%2C552\" width=\"681\" height=\"552\" srcset=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-7.jpg?resize=300%2C243&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-7.jpg?w=552&amp;ssl=1 552w\" sizes=\"auto, (max-width: 681px) 100vw, 681px\" \/><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"3208\" data-permalink=\"https:\/\/www.shqiperia.com\/blog\/piktori-mustafa-arapi-album\/mustafa-arapi-9\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-9.jpg?fit=552%2C449&amp;ssl=1\" data-orig-size=\"552,449\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Mustafa Arapi (9)\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-9.jpg?fit=300%2C244&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-9.jpg?fit=552%2C449&amp;ssl=1\" class=\"alignnone wp-image-3208\" alt=\"\" src=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-9-300x244.jpg?resize=612%2C498\" width=\"612\" height=\"498\" srcset=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-9.jpg?resize=300%2C244&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-9.jpg?w=552&amp;ssl=1 552w\" sizes=\"auto, (max-width: 612px) 100vw, 612px\" \/> <img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"3207\" data-permalink=\"https:\/\/www.shqiperia.com\/blog\/piktori-mustafa-arapi-album\/mustafa-arapi-8\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-8.jpg?fit=542%2C414&amp;ssl=1\" data-orig-size=\"542,414\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Mustafa Arapi (8)\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-8.jpg?fit=300%2C229&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-8.jpg?fit=542%2C414&amp;ssl=1\" class=\"alignnone wp-image-3207\" alt=\"\" src=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-8-300x229.jpg?resize=735%2C561\" width=\"735\" height=\"561\" srcset=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-8.jpg?resize=300%2C229&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-8.jpg?resize=290%2C220&amp;ssl=1 290w, https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-8.jpg?w=542&amp;ssl=1 542w\" sizes=\"auto, (max-width: 735px) 100vw, 735px\" \/><\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"3209\" data-permalink=\"https:\/\/www.shqiperia.com\/blog\/piktori-mustafa-arapi-album\/mustafa-arapi-10\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-10.jpg?fit=552%2C588&amp;ssl=1\" data-orig-size=\"552,588\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Mustafa Arapi (10)\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-10.jpg?fit=282%2C300&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-10.jpg?fit=552%2C588&amp;ssl=1\" class=\"alignnone wp-image-3209\" alt=\"\" src=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-10-282x300.jpg?resize=532%2C566\" width=\"532\" height=\"566\" srcset=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-10.jpg?resize=282%2C300&amp;ssl=1 282w, https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-10.jpg?w=552&amp;ssl=1 552w\" sizes=\"auto, (max-width: 532px) 100vw, 532px\" \/> <img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"3210\" data-permalink=\"https:\/\/www.shqiperia.com\/blog\/piktori-mustafa-arapi-album\/mustafa-arapi-11\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-11.jpg?fit=552%2C378&amp;ssl=1\" data-orig-size=\"552,378\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Mustafa Arapi (11)\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-11.jpg?fit=300%2C205&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-11.jpg?fit=552%2C378&amp;ssl=1\" class=\"alignnone wp-image-3210\" alt=\"\" src=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-11-300x205.jpg?resize=661%2C452\" width=\"661\" height=\"452\" srcset=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-11.jpg?resize=300%2C205&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-11.jpg?resize=135%2C93&amp;ssl=1 135w, https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-11.jpg?w=552&amp;ssl=1 552w\" sizes=\"auto, (max-width: 661px) 100vw, 661px\" \/> <img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"3211\" data-permalink=\"https:\/\/www.shqiperia.com\/blog\/piktori-mustafa-arapi-album\/mustafa-arapi-12\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-12.jpg?fit=541%2C720&amp;ssl=1\" data-orig-size=\"541,720\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Mustafa Arapi (12)\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-12.jpg?fit=225%2C300&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-12.jpg?fit=541%2C720&amp;ssl=1\" class=\"alignnone wp-image-3211\" alt=\"\" src=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-12-225x300.jpg?resize=444%2C592\" width=\"444\" height=\"592\" srcset=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-12.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-12.jpg?w=541&amp;ssl=1 541w\" sizes=\"auto, (max-width: 444px) 100vw, 444px\" \/>\u00a0 \u00a0 \u00a0 \u00a0 <img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"3212\" data-permalink=\"https:\/\/www.shqiperia.com\/blog\/piktori-mustafa-arapi-album\/mustafa-arapi-13\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-13.jpg?fit=549%2C540&amp;ssl=1\" data-orig-size=\"549,540\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Mustafa Arapi (13)\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-13.jpg?fit=300%2C295&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-13.jpg?fit=549%2C540&amp;ssl=1\" class=\"alignnone wp-image-3212\" alt=\"\" src=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-13-300x295.jpg?resize=463%2C455\" width=\"463\" height=\"455\" srcset=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-13.jpg?resize=300%2C295&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-13.jpg?w=549&amp;ssl=1 549w\" sizes=\"auto, (max-width: 463px) 100vw, 463px\" \/> <img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"3213\" data-permalink=\"https:\/\/www.shqiperia.com\/blog\/piktori-mustafa-arapi-album\/mustafa-arapi-14\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-14.jpg?fit=552%2C792&amp;ssl=1\" data-orig-size=\"552,792\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Mustafa Arapi (14)\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-14.jpg?fit=209%2C300&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-14.jpg?fit=552%2C792&amp;ssl=1\" class=\"alignnone wp-image-3213\" alt=\"\" src=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-14-209x300.jpg?resize=369%2C530\" width=\"369\" height=\"530\" srcset=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-14.jpg?resize=209%2C300&amp;ssl=1 209w, https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-14.jpg?w=552&amp;ssl=1 552w\" sizes=\"auto, (max-width: 369px) 100vw, 369px\" \/>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"3214\" data-permalink=\"https:\/\/www.shqiperia.com\/blog\/piktori-mustafa-arapi-album\/mustafa-arapi-15\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-15.jpg?fit=552%2C469&amp;ssl=1\" data-orig-size=\"552,469\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Mustafa Arapi (15)\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-15.jpg?fit=300%2C255&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-15.jpg?fit=552%2C469&amp;ssl=1\" class=\"alignnone wp-image-3214\" alt=\"\" src=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-15-300x255.jpg?resize=502%2C427\" width=\"502\" height=\"427\" srcset=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-15.jpg?resize=300%2C255&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-15.jpg?w=552&amp;ssl=1 552w\" sizes=\"auto, (max-width: 502px) 100vw, 502px\" \/> <img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"3215\" data-permalink=\"https:\/\/www.shqiperia.com\/blog\/piktori-mustafa-arapi-album\/mustafa-arapi-16\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-16.jpg?fit=552%2C462&amp;ssl=1\" data-orig-size=\"552,462\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Mustafa Arapi (16)\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-16.jpg?fit=300%2C251&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-16.jpg?fit=552%2C462&amp;ssl=1\" class=\"alignnone wp-image-3215\" alt=\"\" src=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-16-300x251.jpg?resize=654%2C547\" width=\"654\" height=\"547\" srcset=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-16.jpg?resize=300%2C251&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-16.jpg?w=552&amp;ssl=1 552w\" sizes=\"auto, (max-width: 654px) 100vw, 654px\" \/> <img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"3216\" data-permalink=\"https:\/\/www.shqiperia.com\/blog\/piktori-mustafa-arapi-album\/mustafa-arapi-17\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-17.jpg?fit=552%2C438&amp;ssl=1\" data-orig-size=\"552,438\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Mustafa Arapi (17)\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-17.jpg?fit=300%2C238&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-17.jpg?fit=552%2C438&amp;ssl=1\" class=\"alignnone wp-image-3216\" alt=\"\" src=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-17-300x238.jpg?resize=657%2C521\" width=\"657\" height=\"521\" srcset=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-17.jpg?resize=300%2C238&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-17.jpg?w=552&amp;ssl=1 552w\" sizes=\"auto, (max-width: 657px) 100vw, 657px\" \/><\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"3217\" data-permalink=\"https:\/\/www.shqiperia.com\/blog\/piktori-mustafa-arapi-album\/mustafa-arapi-18\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-18.jpg?fit=541%2C425&amp;ssl=1\" data-orig-size=\"541,425\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Mustafa Arapi (18)\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-18.jpg?fit=300%2C236&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-18.jpg?fit=541%2C425&amp;ssl=1\" class=\"alignnone wp-image-3217\" alt=\"\" src=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-18-300x236.jpg?resize=653%2C514\" width=\"653\" height=\"514\" srcset=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-18.jpg?resize=300%2C236&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-18.jpg?w=541&amp;ssl=1 541w\" sizes=\"auto, (max-width: 653px) 100vw, 653px\" \/> <img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"3218\" data-permalink=\"https:\/\/www.shqiperia.com\/blog\/piktori-mustafa-arapi-album\/mustafa-arapi-19\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-19.jpg?fit=552%2C431&amp;ssl=1\" data-orig-size=\"552,431\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Mustafa Arapi (19)\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-19.jpg?fit=300%2C234&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-19.jpg?fit=552%2C431&amp;ssl=1\" class=\"alignnone wp-image-3218\" alt=\"\" src=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-19-300x234.jpg?resize=656%2C512\" width=\"656\" height=\"512\" srcset=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-19.jpg?resize=300%2C234&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-19.jpg?w=552&amp;ssl=1 552w\" sizes=\"auto, (max-width: 656px) 100vw, 656px\" \/> <img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"3219\" data-permalink=\"https:\/\/www.shqiperia.com\/blog\/piktori-mustafa-arapi-album\/mustafa-arapi-20\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-20.jpg?fit=552%2C437&amp;ssl=1\" data-orig-size=\"552,437\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Mustafa Arapi (20)\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-20.jpg?fit=300%2C238&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-20.jpg?fit=552%2C437&amp;ssl=1\" class=\"alignnone wp-image-3219\" alt=\"\" src=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-20-300x238.jpg?resize=657%2C521\" width=\"657\" height=\"521\" srcset=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-20.jpg?resize=300%2C238&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-20.jpg?w=552&amp;ssl=1 552w\" sizes=\"auto, (max-width: 657px) 100vw, 657px\" \/> <img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"3220\" data-permalink=\"https:\/\/www.shqiperia.com\/blog\/piktori-mustafa-arapi-album\/mustafa-arapi-21\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-21.jpg?fit=552%2C440&amp;ssl=1\" data-orig-size=\"552,440\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Mustafa Arapi (21)\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-21.jpg?fit=300%2C239&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-21.jpg?fit=552%2C440&amp;ssl=1\" class=\"alignnone wp-image-3220\" alt=\"\" src=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-21-300x239.jpg?resize=599%2C477\" width=\"599\" height=\"477\" srcset=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-21.jpg?resize=300%2C239&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-21.jpg?w=552&amp;ssl=1 552w\" sizes=\"auto, (max-width: 599px) 100vw, 599px\" \/> <img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"3221\" data-permalink=\"https:\/\/www.shqiperia.com\/blog\/piktori-mustafa-arapi-album\/mustafa-arapi-22\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-22.jpg?fit=552%2C432&amp;ssl=1\" data-orig-size=\"552,432\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Mustafa Arapi (22)\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-22.jpg?fit=300%2C235&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-22.jpg?fit=552%2C432&amp;ssl=1\" class=\"alignnone wp-image-3221\" alt=\"\" src=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-22-300x235.jpg?resize=604%2C473\" width=\"604\" height=\"473\" srcset=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-22.jpg?resize=300%2C235&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-22.jpg?w=552&amp;ssl=1 552w\" sizes=\"auto, (max-width: 604px) 100vw, 604px\" \/> <img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"3222\" data-permalink=\"https:\/\/www.shqiperia.com\/blog\/piktori-mustafa-arapi-album\/mustafa-arapi-23\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-23.jpg?fit=338%2C280&amp;ssl=1\" data-orig-size=\"338,280\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Mustafa Arapi (23)\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-23.jpg?fit=300%2C249&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-23.jpg?fit=338%2C280&amp;ssl=1\" class=\"alignnone wp-image-3222\" alt=\"\" src=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-23-300x249.jpg?resize=611%2C507\" width=\"611\" height=\"507\" srcset=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-23.jpg?resize=300%2C249&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-23.jpg?w=338&amp;ssl=1 338w\" sizes=\"auto, (max-width: 611px) 100vw, 611px\" \/> <img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"3223\" data-permalink=\"https:\/\/www.shqiperia.com\/blog\/piktori-mustafa-arapi-album\/mustafa-arapi-24\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-24.jpg?fit=496%2C402&amp;ssl=1\" data-orig-size=\"496,402\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Mustafa Arapi (24)\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-24.jpg?fit=300%2C243&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-24.jpg?fit=496%2C402&amp;ssl=1\" class=\"alignnone wp-image-3223\" alt=\"\" src=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-24-300x243.jpg?resize=614%2C497\" width=\"614\" height=\"497\" srcset=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-24.jpg?resize=300%2C243&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-24.jpg?w=496&amp;ssl=1 496w\" sizes=\"auto, (max-width: 614px) 100vw, 614px\" \/> <img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"3224\" data-permalink=\"https:\/\/www.shqiperia.com\/blog\/piktori-mustafa-arapi-album\/mustafa-arapi-25\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-25.jpg?fit=552%2C439&amp;ssl=1\" data-orig-size=\"552,439\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Mustafa Arapi (25)\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-25.jpg?fit=300%2C239&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-25.jpg?fit=552%2C439&amp;ssl=1\" class=\"alignnone wp-image-3224\" alt=\"\" src=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-25-300x239.jpg?resize=542%2C432\" width=\"542\" height=\"432\" srcset=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-25.jpg?resize=300%2C239&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-25.jpg?w=552&amp;ssl=1 552w\" sizes=\"auto, (max-width: 542px) 100vw, 542px\" \/><\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"3225\" data-permalink=\"https:\/\/www.shqiperia.com\/blog\/piktori-mustafa-arapi-album\/mustafa-arapi-27\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-27.jpg?fit=552%2C412&amp;ssl=1\" data-orig-size=\"552,412\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Mustafa Arapi (27)\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-27.jpg?fit=300%2C224&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-27.jpg?fit=552%2C412&amp;ssl=1\" class=\"alignnone wp-image-3225\" alt=\"\" src=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-27-300x224.jpg?resize=540%2C403\" width=\"540\" height=\"403\" srcset=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-27.jpg?resize=300%2C224&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-27.jpg?w=552&amp;ssl=1 552w\" sizes=\"auto, (max-width: 540px) 100vw, 540px\" \/>\u00a0 \u00a0\u00a0<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"3227\" data-permalink=\"https:\/\/www.shqiperia.com\/blog\/piktori-mustafa-arapi-album\/mustafa-arapi-29\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-29.jpg?fit=620%2C447&amp;ssl=1\" data-orig-size=\"620,447\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Mustafa Arapi (29)\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-29.jpg?fit=300%2C216&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-29.jpg?fit=620%2C447&amp;ssl=1\" class=\"alignnone wp-image-3227\" alt=\"\" src=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-29-300x216.jpg?resize=568%2C409\" width=\"568\" height=\"409\" srcset=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-29.jpg?resize=300%2C216&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-29.jpg?w=620&amp;ssl=1 620w\" sizes=\"auto, (max-width: 568px) 100vw, 568px\" \/>\u00a0 <img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"3229\" data-permalink=\"https:\/\/www.shqiperia.com\/blog\/piktori-mustafa-arapi-album\/mustafa-arapi\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi.jpg?fit=533%2C381&amp;ssl=1\" data-orig-size=\"533,381\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Mustafa Arapi\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi.jpg?fit=300%2C214&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi.jpg?fit=533%2C381&amp;ssl=1\" class=\"alignnone wp-image-3229\" alt=\"\" src=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-300x214.jpg?resize=590%2C421\" width=\"590\" height=\"421\" srcset=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi.jpg?resize=300%2C214&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi.jpg?w=533&amp;ssl=1 533w\" sizes=\"auto, (max-width: 590px) 100vw, 590px\" \/><\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"3228\" data-permalink=\"https:\/\/www.shqiperia.com\/blog\/piktori-mustafa-arapi-album\/mustafa-arapi-30\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-30.jpg?fit=282%2C383&amp;ssl=1\" data-orig-size=\"282,383\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Mustafa Arapi (30)\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-30.jpg?fit=221%2C300&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-30.jpg?fit=282%2C383&amp;ssl=1\" class=\"alignnone wp-image-3228\" alt=\"\" src=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-30-221x300.jpg?resize=425%2C577\" width=\"425\" height=\"577\" srcset=\"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-30.jpg?resize=221%2C300&amp;ssl=1 221w, https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-30.jpg?w=282&amp;ssl=1 282w\" sizes=\"auto, (max-width: 425px) 100vw, 425px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mustafa Arapi ka lindur m\u00eb 23 korrik 1950 n\u00eb Tiran\u00eb. Ai u diplomua n\u00eb Akademin\u00eb e Arteve n\u00eb vitin 1979 p\u00ebr piktur\u00eb. Pas studimeve ai filloi t\u00eb punonte si restaurues i veprave t\u00eb artit bizantin n\u00eb Institutin e Monumenteve t\u00eb Kultur\u00ebs n\u00eb Tiran\u00eb. Ka punuar si profesor n\u00eb Akademin\u00eb e Arteve nga viti 1985 deri [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":3200,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[87],"tags":[],"class_list":["post-3199","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arte"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/02\/Mustafa-Arapi-26.jpg?fit=551%2C389&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p5Z6wp-PB","jetpack-related-posts":[{"id":35117,"url":"https:\/\/www.shqiperia.com\/blog\/mustafa-arapi-galeria-e-arteve-eshte-kthyer-ne-bunker-po-promovohen-njerez-te-panjohur-artistet-te-mos-rrine-indiferente\/","url_meta":{"origin":3199,"position":0},"title":"Mustafa Arapi: &#8211; Galeria e Arteve \u00ebsht\u00eb kthyer n\u00eb bunker, po promovohen njer\u00ebz t\u00eb panjohur, artist\u00ebt t\u00eb mos rrin\u00eb indiferent\u00eb","author":"Kurt Farka","date":"May 27, 2020","format":false,"excerpt":"Mustafa Arapi: - Galeria e Arteve \u00ebsht\u00eb kthyer n\u00eb bunker, po promovohen njer\u00ebz t\u00eb panjohur, artist\u00ebt t\u00eb mos rrin\u00eb indiferent\u00eb 15\/12\/2019 Piktori i njohur Mustafa Arapi shprehet se p\u00ebr jet\u00ebn artistike n\u00eb vend, nuk ka v\u00ebmendje nga institucionet. Me probleme ai shikon jo vet\u00ebm se si funksionon sot Galeria Komb\u00ebtare\u2026","rel":"","context":"In &quot;Arte&quot;","block_context":{"text":"Arte","link":"https:\/\/www.shqiperia.com\/blog\/category\/arte\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2020\/05\/Mustafa-Arapi-1.jpg?fit=395%2C216&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":34233,"url":"https:\/\/www.shqiperia.com\/blog\/mustafa-arapi-na-mungon-nje-muze-kombetar-i-etnografise-shteti-te-mendoje-per-ndertimin-e-tij\/","url_meta":{"origin":3199,"position":1},"title":"Mustafa Arapi: &#8211; Na mungon nj\u00eb muze komb\u00ebtar i etnografis\u00eb, shteti t\u00eb mendoj\u00eb p\u00ebr nd\u00ebrtimin e tij","author":"Kurt Farka","date":"May 4, 2020","format":false,"excerpt":"Mustafa Arapi: - Na mungon nj\u00eb muze komb\u00ebtar i etnografis\u00eb, shteti t\u00eb mendoj\u00eb p\u00ebr nd\u00ebrtimin e tij 30 PRILL 2020 Muzeu komb\u00ebtar i etnografis\u00eb mungon n\u00eb vendin ton\u00eb. Edhe pse \u00ebsht\u00eb folur p\u00ebr nj\u00eb pavijon, q\u00eb do t\u00eb sh\u00ebrbente si muze, deri tani asgj\u00eb nuk \u00ebsht\u00eb prezantuar nga institucionet. Emra\u2026","rel":"","context":"In &quot;Blogu i Udh\u00ebtarit&quot;","block_context":{"text":"Blogu i Udh\u00ebtarit","link":"https:\/\/www.shqiperia.com\/blog\/category\/blogu-i-udhetarit\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2020\/05\/Mustafa-Arapi.jpg?fit=800%2C533&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2020\/05\/Mustafa-Arapi.jpg?fit=800%2C533&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2020\/05\/Mustafa-Arapi.jpg?fit=800%2C533&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2020\/05\/Mustafa-Arapi.jpg?fit=800%2C533&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":43236,"url":"https:\/\/www.shqiperia.com\/blog\/mustafa-arapi-album-peisazhe\/","url_meta":{"origin":3199,"position":2},"title":"Mustafa Arapi. Album: Peisazhe.","author":"Kurt Farka","date":"January 23, 2021","format":false,"excerpt":"Mustafa Arapi. Album: Peisazhe. - U nda nga jeta Mustafa Arapi, Studiuesi i Artit Mesjetar, Restauratori i kualifikuar, Piktori i Peisazhit dhe mjeshterise se Ngjyrave, Petagogu. Peisazhet i mora nga FB, jane nga ekspozita e hapur nga Mustafai ne Galerine Kombetare te Arteve, shtator 2010. Gjithe Drite jane, Drite paste.","rel":"","context":"In &quot;Arte&quot;","block_context":{"text":"Arte","link":"https:\/\/www.shqiperia.com\/blog\/category\/arte\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2021\/01\/Mustafa-ArapiShtator-2010-Foto-J.-Brahaj.jpg?fit=720%2C584&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2021\/01\/Mustafa-ArapiShtator-2010-Foto-J.-Brahaj.jpg?fit=720%2C584&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2021\/01\/Mustafa-ArapiShtator-2010-Foto-J.-Brahaj.jpg?fit=720%2C584&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2021\/01\/Mustafa-ArapiShtator-2010-Foto-J.-Brahaj.jpg?fit=720%2C584&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":10990,"url":"https:\/\/www.shqiperia.com\/blog\/galeri-portrte-nga-mikel-temo\/","url_meta":{"origin":3199,"position":3},"title":"Galeri: &#8211; Portrete nga Mikel Temo. =","author":"Kurt Farka","date":"August 25, 2018","format":false,"excerpt":"Galeri: - Portrte nga Mikel Temo. = Mikel Temo i lindur m\u00eb 1964 n\u00eb Kor\u00e7\u00eb \u00ebsht\u00eb piktor dhe stilist shqiptar me banim n\u00eb Kanada. Diplomohet n\u00eb deg\u00ebn Piktur\u00eb Monumentale dhe Vizatim n\u00eb Akademin\u00eb e Arteve n\u00eb Tiran\u00eb, Shqip\u00ebri n\u00eb vitin 1986, pas trajnimit n\u00eb nj\u00eb program intensiv n\u00eb artin tradicional\u2026","rel":"","context":"In &quot;Arte&quot;","block_context":{"text":"Arte","link":"https:\/\/www.shqiperia.com\/blog\/category\/arte\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2018\/08\/39522522_10156208228252561_6785780918721183744_n-Copy.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":100155,"url":"https:\/\/www.shqiperia.com\/blog\/kullat-e-boshta-dhe-xhepat-e-zbrazet-pied-a-terre-ne-tirane\/","url_meta":{"origin":3199,"position":4},"title":"Kullat e boshta dhe xhepat e zbraz\u00ebt: &#8211; Pied-\u00e0-terre n\u00eb Tiran\u00eb","author":"Kurt Farka","date":"May 12, 2026","format":false,"excerpt":"12 Maji 2026 Nga: Adrian Thano Ekuilibri \u00ebsht\u00eb zgjidhja. Nj\u00eb shoq\u00ebri e sh\u00ebndetshme nuk duhet as t\u00eb adhuroj\u00eb miliarder\u00ebt si per\u00ebndi dhe as t\u2019i trajtoj\u00eb k\u00ebta si armiq publik\u00eb. Pasuria duhet t\u00eb mbaj\u00eb p\u00ebrgjegj\u00ebsi, taksa duhet t\u00eb mbetet instrument ekonomie. K\u00ebtu vijm\u00eb te p\u00ebrshtatja e k\u00ebtij debati n\u00eb aktualitetin shqiptar.\u2026","rel":"","context":"In &quot;Blogu i Udh\u00ebtarit&quot;","block_context":{"text":"Blogu i Udh\u00ebtarit","link":"https:\/\/www.shqiperia.com\/blog\/category\/blogu-i-udhetarit\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2026\/05\/Screenshot_20260511_134013_Gallery.jpg?fit=720%2C494&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2026\/05\/Screenshot_20260511_134013_Gallery.jpg?fit=720%2C494&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2026\/05\/Screenshot_20260511_134013_Gallery.jpg?fit=720%2C494&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2026\/05\/Screenshot_20260511_134013_Gallery.jpg?fit=720%2C494&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":100179,"url":"https:\/\/www.shqiperia.com\/blog\/shifrat-perhapje-masive-e-kokaines-dhe-e-prostitucionit-jo-vetem-ne-tirane\/","url_meta":{"origin":3199,"position":5},"title":"SHIFRAT: P\u00ebrhapje masive e kokain\u00ebs dhe e prostitucionit jo vet\u00ebm n\u00eb Tiran\u00eb","author":"Kurt Farka","date":"May 12, 2026","format":false,"excerpt":"12 Maji 2026 Nga Gjergj Erebara Gjat\u00eb muajit prill, nj\u00eb num\u00ebr i pazakont\u00eb informacionesh t\u00eb publikuara nga Policia e Shtetit, krijojn\u00eb nj\u00eb panoram\u00eb shqet\u00ebsuese p\u00ebr p\u00ebrhapjen masive t\u00eb konsumimit t\u00eb kokain\u00ebs, jo vet\u00ebm te ish-Blloku n\u00eb Tiran\u00eb, por pothuajse n\u00eb t\u00eb gjith\u00eb Shqip\u00ebrin\u00eb. P\u00ebrhapja e kokain\u00ebs duket se ka ecur\u2026","rel":"","context":"In &quot;Blogu i Udh\u00ebtarit&quot;","block_context":{"text":"Blogu i Udh\u00ebtarit","link":"https:\/\/www.shqiperia.com\/blog\/category\/blogu-i-udhetarit\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2026\/05\/Lende-narkotike-1140x760-1.jpg?fit=1140%2C760&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2026\/05\/Lende-narkotike-1140x760-1.jpg?fit=1140%2C760&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2026\/05\/Lende-narkotike-1140x760-1.jpg?fit=1140%2C760&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2026\/05\/Lende-narkotike-1140x760-1.jpg?fit=1140%2C760&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.shqiperia.com\/blog\/wp-content\/uploads\/2026\/05\/Lende-narkotike-1140x760-1.jpg?fit=1140%2C760&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.shqiperia.com\/blog\/wp-json\/wp\/v2\/posts\/3199","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.shqiperia.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.shqiperia.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.shqiperia.com\/blog\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.shqiperia.com\/blog\/wp-json\/wp\/v2\/comments?post=3199"}],"version-history":[{"count":2,"href":"https:\/\/www.shqiperia.com\/blog\/wp-json\/wp\/v2\/posts\/3199\/revisions"}],"predecessor-version":[{"id":43250,"href":"https:\/\/www.shqiperia.com\/blog\/wp-json\/wp\/v2\/posts\/3199\/revisions\/43250"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.shqiperia.com\/blog\/wp-json\/wp\/v2\/media\/3200"}],"wp:attachment":[{"href":"https:\/\/www.shqiperia.com\/blog\/wp-json\/wp\/v2\/media?parent=3199"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.shqiperia.com\/blog\/wp-json\/wp\/v2\/categories?post=3199"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.shqiperia.com\/blog\/wp-json\/wp\/v2\/tags?post=3199"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}